{"id":1339,"date":"2018-04-10T21:52:01","date_gmt":"2018-04-10T19:52:01","guid":{"rendered":"https:\/\/www.atobeiratenis.com\/2018\/04\/10\/que-las-raquetas-de-alta-competicion-son-rigidas-y-no-flexibles\/"},"modified":"2018-04-10T21:52:01","modified_gmt":"2018-04-10T19:52:01","slug":"que-las-raquetas-de-alta-competicion-son-rigidas-y-no-flexibles","status":"publish","type":"post","link":"https:\/\/www.atobeiratenis.com\/en\/2018\/04\/10\/que-las-raquetas-de-alta-competicion-son-rigidas-y-no-flexibles\/","title":{"rendered":"\u00bfQue las raquetas de alta competici\u00f3n son r\u00edgidas y no flexibles?"},"content":{"rendered":"<table border=\"\\\\\\\"0\\\\\\\"\" width=\"\\\\\\\"410\\\\\\\"\" cellspacing=\"\\\\\\\"cellpadding =\"\\\\\\\" align=\"\\\\\\\"center\\\\\\\"\">\n<tbody>\n<tr>\n<td class=\"\\\\\\\"texto12blancobold\\\\\\\"\" align=\"\\\\\\\"left\\\\\\\"\" valign=\"\\\\\\\"middle\\\\\\\"\"><\/td>\n<\/tr>\n<tr>\n<td class=\"\\\\\\\"texto11grisnorm\\\\\\\"\" align=\"\\\\\\\"left\\\\\\\"\" valign=\"\\\\\\\"middle\\\\\\\"\"><a href=\"\/en\/\"https:><img class=\"\\\\\\\"alignnone\" size-full wp-image-1340\\\\\\\" src=\"\\\\\\\"https:><\/a>El desconocimiento generalizado, a\u00fan de muchos que viven del tenis como jugadores profesionales, entrenadores y profesores, ha generado una pol\u00e9mica acerca de las caracter\u00edsticas de las raquetas de competici\u00f3n.<\/p>\n<p>Si bien en n\u00fameros anteriores se han difundido conceptos que abordan este tema, incluso un sistema de selecci\u00f3n de raquetas con pautas para que cada jugador pueda encasillarse en el perfil de raqueta que le corresponde, nos proponemos sistematizar prolijamente los conceptos para contribuir definitivamente al esclarecimiento de esta tem\u00e1tica.<\/p>\n<p>Ordinariamente se asocia una raqueta de m\u00e1xima competici\u00f3n con dureza y rigidez, lo que es absolutamente err\u00f3neo.<\/p>\n<p>Largas e in\u00fatiles charlas, con bibliograf\u00eda en la mano\u00a0 que contrar\u00edan estos argumentos, son deso\u00edas y rechazadas por una multitud de \\\\\\\u00bbautodidactas\\\\\\\u00bb que insisten en el equ\u00edvoco<\/p>\n<p>No ser\u00e1 f\u00e1cil convencer a quienes han mamado esta falacia y quien esto escribe no tiene otra pretensi\u00f3n que aclarar conceptos para as\u00ed poder expresarnos correctamente y a la vez evitar malos entendidos.<\/p>\n<p>En primer t\u00e9rmino, se\u00f1alemos los diferentes tipos de raqueta adecuados a las habilidades, t\u00e9cnica\u00a0 y caracter\u00edsticas de juego de cada jugador.<br \/>\nLas raquetas de competici\u00f3n son para jugadores con golpes largos, de alta t\u00e9cnica y de alta velocidad, con buen toque y juego de precisi\u00f3n.<br \/>\nLas raquetas de aficionados son las adecuadas para aqu\u00e9llos que tienen golpes cortos,\u00a0 compactos y de baja velocidad. Por ello necesitan de una raqueta de gran potencia, que despida y que sea muy maniobrable y ligera de peso. A la vez tolerante con los golpes descentrados (forgiving) &#8211; lo que se consigue con una raqueta de sweet spot m\u00e1s grande-\u00a0 y propiedades de amortiguaci\u00f3n para generar un mayor confort.\u00a0<span style=\"\\\\\\\"font-size:\" medium;\\\\\\\">Ellos necesitan de raquetas r\u00edgidas que generan una mayor aceleraci\u00f3n de pelota.<\/span><\/p>\n<p>Ello no obsta que haya jugadores profesionales, generalmente mujeres y veteranos,\u00a0 que puedan usar raquetas que no respondan a los lineamientos de un modelo\u00a0 de competici\u00f3n.<\/p>\n<p>Por supuesto, he descripto las casos extremos, pues entre ambos existe un enorme espectro de jugadores, que podr\u00edamos llamar intermedios y a\u00fan dentro de \u00e9stos notorias diferencias de niveles.<br \/>\nPor ello algunas marcas categorizan los modelos numer\u00e1ndolos del 1 al 10, es decir, ofreciendo diez variables para satisfacer las diferentes necesidades y exigencias.<\/p>\n<p>1) CONSTRUCCION O DISE\u00d1O DEL MARCO<\/p>\n<p>\u2022\u00a0\u00a0 \u00a0Constant beam (ilustraci\u00f3n 1) o vara de altura uniforme. En las de competici\u00f3n son de perfil fino y de grosor constante del marco para generar el comportamiento flexible de la raqueta al prolongar el tiempo de contacto pelota\/encordado, optimizando toque y control. (ilustraci\u00f3n 2)<br \/>\n\u2022\u00a0\u00a0 \u00a0Variable high beam o vara de altura variable, el marco es m\u00e1s r\u00edgido en algunos sectores, pudiendo ser el extremo de la cabeza y\u00a0 el mango, generando rigidez y estabilidad necesarias para mayor potencia y confort. (ilustraci\u00f3n 3)<\/p>\n<p>2) MATERIALES UTILIZADOS<\/p>\n<p>Las raquetas de calidad pueden estar constru\u00eddas con diferentes materiales :Grafito de alto m\u00f3dulo (HMG), grafito, titanio, kevlar, fibra de vidrio, etc. pero nunca aluminio.<br \/>\nSi bien en las raquetas de competici\u00f3n se pueden estar emplear los mismos materiales que en las de aficionados, lo que cambia son los porcentajes utilizados de cada uno de ellas. As\u00ed la mayor\u00eda de las raquetas de competici\u00f3n llevan grafito com\u00fan que es menos duro que el grafito de alto m\u00f3dulo que se utiliza en las mejores raquetas de aficionados. Pero si un modelo de competici\u00f3n llevara HMG lo har\u00eda siempre en un bajo porcentaje,<br \/>\nLa fibra de vidrio se utiliza en las raquetas de competici\u00f3n para otorgar mayor flexibilidad.<\/p>\n<p>Los fabricantes son renuentes a publicitar los porcentajes de cada material utilizado en los distintos modelos.<\/p>\n<p>Quiz\u00e1s debamos buscar la ra\u00edz de este malentendido en que algunos confunden rigidez con peso. Ciertamente las de competici\u00f3n son m\u00e1s pesadas a la vez que m\u00e1s flexibles.<br \/>\nProbablemente todo sea producto de una err\u00f3nea asociaci\u00f3n.<\/p>\n<p>Espero con esta explicaci\u00f3n dejar aclarado este tema, aunque tengo mis serias dudas, al menos en mis facultades did\u00e1cticas.<\/p>\n<p>Deseo aclarar que la gran variedad de los conceptos aqu\u00ed vertidos no son de mi autor\u00eda, por el contrario pertencen a especialistas en la materia que he obtenido de fuentes bibliogr\u00e1ficas.<\/p>\n<p>De todos modos adhiero a lo expuesto pues considero que lo argumentado tambi\u00e9n est\u00e1 respaldado por el sentido com\u00fan.<\/p>\n<p>Ernesto Socolovsky<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Texto extra\u00eddo de\u00a0http:\/\/www.eximtrade.com.ar\/home\/noticia.php?noticia_id=46<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>El desconocimiento generalizado, a\u00fan de muchos que viven del tenis como jugadores profesionales, entrenadores y profesores, ha generado una pol\u00e9mica acerca de las caracter\u00edsticas de las raquetas de competici\u00f3n. Si bien en n\u00fameros anteriores se han difundido conceptos que abordan este tema, incluso un sistema de selecci\u00f3n de raquetas con pautas para que cada jugador [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[4,10,11,13],"tags":[18,30,51,69,95,107],"class_list":["post-1339","post","type-post","status-publish","format-standard","hentry","category-conocimiento","category-tenis-2","category-test-material-deportivo","category-uncategorized","tag-atobeira-2","tag-clases-de-tenis","tag-escuela-de-tenis","tag-nigran","tag-tenis","tag-vigo"],"_links":{"self":[{"href":"https:\/\/www.atobeiratenis.com\/en\/wp-json\/wp\/v2\/posts\/1339","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.atobeiratenis.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.atobeiratenis.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.atobeiratenis.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.atobeiratenis.com\/en\/wp-json\/wp\/v2\/comments?post=1339"}],"version-history":[{"count":0,"href":"https:\/\/www.atobeiratenis.com\/en\/wp-json\/wp\/v2\/posts\/1339\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.atobeiratenis.com\/en\/wp-json\/wp\/v2\/media?parent=1339"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.atobeiratenis.com\/en\/wp-json\/wp\/v2\/categories?post=1339"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.atobeiratenis.com\/en\/wp-json\/wp\/v2\/tags?post=1339"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}